{"id":814,"count":24,"description":"","link":"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/","name":"Travel Tips","slug":"travel-tips","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Travel Tips Archives - Vintage Travel - Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel Tips Archives - Vintage Travel - Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage Travel - Blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/\",\"url\":\"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/\",\"name\":\"Travel Tips Archives - Vintage Travel - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.vintagetravel.co.uk\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vintagetravel.co.uk\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel Tips\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vintagetravel.co.uk\/blog\/#website\",\"url\":\"https:\/\/www.vintagetravel.co.uk\/blog\/\",\"name\":\"Vintage Travel - Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vintagetravel.co.uk\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel Tips Archives - Vintage Travel - Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Travel Tips Archives - Vintage Travel - Blog","og_url":"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/","og_site_name":"Vintage Travel - Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/","url":"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/","name":"Travel Tips Archives - Vintage Travel - Blog","isPartOf":{"@id":"https:\/\/www.vintagetravel.co.uk\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vintagetravel.co.uk\/blog\/category\/travel-tips\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vintagetravel.co.uk\/blog\/"},{"@type":"ListItem","position":2,"name":"Travel Tips"}]},{"@type":"WebSite","@id":"https:\/\/www.vintagetravel.co.uk\/blog\/#website","url":"https:\/\/www.vintagetravel.co.uk\/blog\/","name":"Vintage Travel - Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vintagetravel.co.uk\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.vintagetravel.co.uk\/blog\/wp-json\/wp\/v2\/categories\/814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vintagetravel.co.uk\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.vintagetravel.co.uk\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.vintagetravel.co.uk\/blog\/wp-json\/wp\/v2\/posts?categories=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}